{"id":24872,"date":"2025-10-20T16:43:23","date_gmt":"2025-10-20T16:43:23","guid":{"rendered":"https:\/\/blockchainjournal.news\/es\/?p=24872"},"modified":"2025-10-20T16:43:26","modified_gmt":"2025-10-20T16:43:26","slug":"fallo-del-servicio-externo-impide-generar-la-noticia-elija-como-proceder","status":"publish","type":"post","link":"https:\/\/blockchainjournal.news\/es\/fallo-del-servicio-externo-impide-generar-la-noticia-elija-como-proceder\/","title":{"rendered":"El potencial de la computadora cu\u00e1ntica y sus l\u00edmites"},"content":{"rendered":"<p data-start=\"2135\" data-end=\"2598\">El cofundador de una firma destacada en an\u00e1lisis de criptomonedas ha declarado que la computaci\u00f3n cu\u00e1ntica representa la mayor amenaza a largo plazo para Bitcoin. Seg\u00fan su an\u00e1lisis, los fundamentos criptogr\u00e1ficos que protegen a Bitcoin \u2014especialmente la relaci\u00f3n entre claves privadas y p\u00fablicas\u2014 podr\u00edan quedar vulnerables ante m\u00e1quinas cu\u00e1nticas, lo cual plantear\u00eda un riesgo directo a los fondos de los usuarios y al sistema en su conjunto.<\/p>\n<p><!--more--><\/p>\n<p data-start=\"2600\" data-end=\"3425\">El problema central radica en c\u00f3mo funciona la seguridad de Bitcoin: una clave privada se utiliza para derivar una clave p\u00fablica mediante matem\u00e1ticas de curva el\u00edptica; mientras esa operaci\u00f3n inversa siga siendo inviable con computadoras cl\u00e1sicas, el sistema se mantiene seguro.\u00a0 Pero <a href=\"https:\/\/murmurationstwo.substack.com\/p\/bitcoin-and-the-quantum-problem-part\" target=\"_blank\" rel=\"noopener\">la computaci\u00f3n cu\u00e1ntica promete alterar ese escenario<\/a>.<\/p>\n<p data-start=\"2600\" data-end=\"3425\">Cuando una m\u00e1quina cu\u00e1ntica pueda derivar claves privadas desde claves p\u00fablicas en tiempos pr\u00e1cticos, el modelo de \u201cfunci\u00f3n unidireccional\u201d quedar\u00e1 roto. El analista destaca que cuando una direcci\u00f3n de Bitcoin gasta su saldo, su clave p\u00fablica queda visible en la red, lo que incrementa su exposici\u00f3n.<\/p>\n<p data-start=\"2600\" data-end=\"3425\">Antes de gastar, muchas direcciones permanecen con la clave p\u00fablica oculta (hash), lo que reduce el riesgo directo, pero ese periodo de seguridad no es eterno.<\/p>\n<h2 data-start=\"2600\" data-end=\"3425\">La computaci\u00f3n cu\u00e1ntica es el mayor riesgo para Bitcoin<\/h2>\n<p data-start=\"3427\" data-end=\"4245\">Insiste en que esto <strong data-start=\"3447\" data-end=\"3453\">no<\/strong> es ciencia ficci\u00f3n, sino un riesgo real que requiere preparaci\u00f3n. Desarrolladores, participantes del nodo, comunidad cripto y usuarios deben considerar urgente el despliegue de <a href=\"https:\/\/blockchainjournal.news\/es\/el-salvador-fragmenta-su-reserva-de-bitcoin-ante-riesgo-cuantico-y-busca-mayor-resiliencia\/\" target=\"_blank\" rel=\"noopener\">criptograf\u00eda post-cu\u00e1ntic<\/a>a, esquemas de firma alternativos y rutas de migraci\u00f3n para monedas que han \u201cexpuesto\u201d sus claves p\u00fablicas. Aunque los ataques cu\u00e1nticos todav\u00eda son te\u00f3ricos hoy, la ventana de preparaci\u00f3n es limitada.<\/p>\n<p data-start=\"3427\" data-end=\"4245\">Cuanto m\u00e1s tiempo se prolongue el uso o la reutilizaci\u00f3n de direcciones, mayor ser\u00e1 el volumen de fondos vulnerables. En resumen: la confianza de Bitcoin \u2014dependiente de matem\u00e1ticas robustas y descentralizaci\u00f3n\u2014 debe evolucionar. Si no lo hace, el mayor desaf\u00edo al que podr\u00eda enfrentarse no ser\u00e1 otra cadena de bloques, ni regulaci\u00f3n, ni macrochoque, sino la propia computaci\u00f3n cu\u00e1ntica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cofundador de una firma destacada en an\u00e1lisis de criptomonedas ha declarado que la computaci\u00f3n cu\u00e1ntica representa la mayor amenaza a largo plazo para Bitcoin. Seg\u00fan su an\u00e1lisis, los fundamentos criptogr\u00e1ficos que protegen a Bitcoin \u2014especialmente la relaci\u00f3n entre claves privadas y p\u00fablicas\u2014 podr\u00edan quedar vulnerables ante m\u00e1quinas cu\u00e1nticas, lo cual plantear\u00eda un riesgo directo<\/p>\n","protected":false},"author":29,"featured_media":24871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1165],"tags":[222,201,2701,59],"class_list":{"0":"post-24872","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-companias","8":"tag-bitcoin","9":"tag-blockchain","10":"tag-computacion-cuantica","11":"tag-featured"},"_links":{"self":[{"href":"https:\/\/blockchainjournal.news\/es\/wp-json\/wp\/v2\/posts\/24872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blockchainjournal.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blockchainjournal.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blockchainjournal.news\/es\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/blockchainjournal.news\/es\/wp-json\/wp\/v2\/comments?post=24872"}],"version-history":[{"count":0,"href":"https:\/\/blockchainjournal.news\/es\/wp-json\/wp\/v2\/posts\/24872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blockchainjournal.news\/es\/wp-json\/wp\/v2\/media\/24871"}],"wp:attachment":[{"href":"https:\/\/blockchainjournal.news\/es\/wp-json\/wp\/v2\/media?parent=24872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blockchainjournal.news\/es\/wp-json\/wp\/v2\/categories?post=24872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blockchainjournal.news\/es\/wp-json\/wp\/v2\/tags?post=24872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}